{"id":14049,"count":1,"description":"","link":"https:\/\/videotecadelcine.net\/index.php\/director\/paul-dano\/","name":"Paul Dano","slug":"paul-dano","taxonomy":"dtdirector","meta":[],"_links":{"self":[{"href":"https:\/\/videotecadelcine.net\/index.php\/wp-json\/wp\/v2\/dtdirector\/14049"}],"collection":[{"href":"https:\/\/videotecadelcine.net\/index.php\/wp-json\/wp\/v2\/dtdirector"}],"about":[{"href":"https:\/\/videotecadelcine.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/dtdirector"}]}}